{"id":6283,"date":"2020-02-10T17:43:59","date_gmt":"2020-02-10T16:43:59","guid":{"rendered":"https:\/\/993.it\/?page_id=6283"},"modified":"2026-07-24T18:27:26","modified_gmt":"2026-07-24T16:27:26","slug":"biologico","status":"publish","type":"page","link":"https:\/\/993.it\/pt\/biologico\/","title":{"rendered":"Biol\u00f3gico"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeIn fadeIn\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a data-rel=\"prettyPhoto[rel-6283-2365749557]\" href=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/24-mesi-BIO-2026.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey prettyphoto\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/24-mesi-BIO-2026.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"24-mesi-BIO-2026\" srcset=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/24-mesi-BIO-2026.jpg 960w, https:\/\/993.it\/wp-content\/uploads\/2026\/07\/24-mesi-BIO-2026-300x200.jpg 300w, https:\/\/993.it\/wp-content\/uploads\/2026\/07\/24-mesi-BIO-2026-768x512.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeIn fadeIn\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a data-rel=\"prettyPhoto[rel-6283-2932284527]\" href=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/Ottavo-di-forma-BIO-nuovo-Certificatore-2026.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey prettyphoto\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"640\" src=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/Ottavo-di-forma-BIO-nuovo-Certificatore-2026.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"Ottavo-di-forma-BIO-nuovo-Certificatore-2026\" srcset=\"https:\/\/993.it\/wp-content\/uploads\/2026\/07\/Ottavo-di-forma-BIO-nuovo-Certificatore-2026.jpg 960w, https:\/\/993.it\/wp-content\/uploads\/2026\/07\/Ottavo-di-forma-BIO-nuovo-Certificatore-2026-300x200.jpg 300w, https:\/\/993.it\/wp-content\/uploads\/2026\/07\/Ottavo-di-forma-BIO-nuovo-Certificatore-2026-768x512.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify;\"><span style=\"font-family: Rubik; font-size: 14pt;\">Nel rispetto del disciplinare biologico, in un equilibrio perfetto con la natura che ci circonda, il caseificio Cavola 993 propone un Parmigiano Reggiano Bio con stagionatura di 24 mesi.<br \/>\nLe propriet\u00e0 organolettiche del Parmigiano Reggiano DOP rimangono inalterate, ma con il valore aggiunto del biologico.<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_center  wpb_animate_when_almost_visible wpb_fadeIn fadeIn\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a data-rel=\"prettyPhoto[rel-6283-884928738]\" href=\"https:\/\/993.it\/wp-content\/uploads\/2020\/03\/24-bio.png\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey prettyphoto\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"147\" src=\"https:\/\/993.it\/wp-content\/uploads\/2020\/03\/24-bio.png\" class=\"vc_single_image-img attachment-full\" alt=\"\" title=\"24-bio\" srcset=\"https:\/\/993.it\/wp-content\/uploads\/2020\/03\/24-bio.png 400w, https:\/\/993.it\/wp-content\/uploads\/2020\/03\/24-bio-300x110.png 300w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Nel rispetto del disciplinare biologico, in un equilibrio perfetto con la natura che ci circonda, il caseificio Cavola 993 propone un Parmigiano Reggiano Bio con stagionatura di 24 mesi. Le propriet\u00e0 organolettiche del Parmigiano Reggiano DOP rimangono inalterate, ma con il valore aggiunto del biologico.","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"rs_blank_template":"","rs_page_bg_color":"","slide_template_v7":"","footnotes":""},"class_list":["post-6283","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/pages\/6283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/comments?post=6283"}],"version-history":[{"count":18,"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/pages\/6283\/revisions"}],"predecessor-version":[{"id":17164,"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/pages\/6283\/revisions\/17164"}],"wp:attachment":[{"href":"https:\/\/993.it\/pt\/wp-json\/wp\/v2\/media?parent=6283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}